{"id":29523,"date":"2025-04-29T12:24:00","date_gmt":"2025-04-29T10:24:00","guid":{"rendered":"https:\/\/www.e-kern.com\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/"},"modified":"2026-02-17T08:42:35","modified_gmt":"2026-02-17T07:42:35","slug":"kern-reconnu-comme-un-leader-mondial-des-services-linguistiques","status":"publish","type":"post","link":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/","title":{"rendered":"KERN reconnu comme un leader mondial des services linguistiques"},"content":{"rendered":"<p>KERN Global Language Services a \u00e9t\u00e9 reconnu par l\u2019institut international de recherche de march\u00e9 <strong>Nimdzi <\/strong>comme l\u2019un des plus <strong>grands prestataires de services linguistiques au monde<\/strong>. Son classement parmi les 75 premiers dans le dernier rapport Nimdzi souligne la position de march\u00e9 solide de l\u2019entreprise en tant que fournisseur de r\u00e9f\u00e9rence pour la gestion linguistique professionnelle et les technologies de traduction innovantes \u00e0 l\u2019\u00e9chelle mondiale. <\/p>\n<p>Ce classement constitue une preuve impressionnante de l\u2019engagement constant de KERN en faveur de la qualit\u00e9, de son expertise approfondie et de sa capacit\u00e9 <strong>d\u2019innovation technologique<\/strong>, qui lui permettent de soutenir ses clients dans le monde entier. Fort de plusieurs d\u00e9cennies d\u2019exp\u00e9rience, KERN d\u00e9montre une fois de plus sa pertinence sur le <strong>march\u00e9 international<\/strong> \u2013 tant dans les services linguistiques classiques que dans le d\u00e9veloppement de solutions bas\u00e9es sur <strong>l\u2019IA pour des strat\u00e9gies de communication<\/strong> et de traduction tourn\u00e9es vers l\u2019avenir. <\/p>\n<p>\u00ab \u00catre class\u00e9 parmi les 75 premiers par Nimdzi est une reconnaissance particuli\u00e8re pour toute notre \u00e9quipe et la strat\u00e9gie que nous poursuivons \u00bb, d\u00e9clare le Dr Thomas Kern, membre du directoire de KERN Global Language Services. \u00ab Notre mission est de rendre la communication mondiale efficace, s\u00e9curis\u00e9e et fluide \u2013 gr\u00e2ce \u00e0 des technologies de pointe, des solutions personnalis\u00e9es et une compr\u00e9hension approfondie des besoins des entreprises internationales. \u00bb <\/p>\n<p>Les d\u00e9veloppements technologiques de KERN se concentrent sur des processus de traduction assist\u00e9s par l\u2019IA, une gestion terminologique adapt\u00e9e aux clients et des solutions d\u2019automatisation intelligentes. Celles-ci offrent aux entreprises internationales une infrastructure linguistique optimis\u00e9e et \u00e9volutive. Gr\u00e2ce \u00e0 ces outils, les entreprises peuvent conqu\u00e9rir plus rapidement de nouveaux march\u00e9s, r\u00e9pondre aux exigences de conformit\u00e9 et garantir une communication fluide dans toutes les langues \u2013 qu\u2019il s\u2019agisse de documentation technique, de campagnes marketing, de rapports financiers ou de contenus sensibles sur le plan juridique. <\/p>\n<p>Un autre avantage essentiel des solutions technologiques de KERN r\u00e9side dans le strict respect des normes les plus \u00e9lev\u00e9es en mati\u00e8re de s\u00e9curit\u00e9 et de protection des donn\u00e9es. Contrairement \u00e0 de nombreux prestataires internationaux, tous les processus sont ex\u00e9cut\u00e9s exclusivement sur des serveurs situ\u00e9s en Allemagne, ce qui permet aux entreprises de b\u00e9n\u00e9ficier de technologies d\u2019IA <strong>conformes au RGPD<\/strong> \u2013 sans risque d\u2019acc\u00e8s ou de r\u00e9utilisation de donn\u00e9es sensibles. KERN \u00e9tablit ainsi de nouvelles r\u00e9f\u00e9rences en mati\u00e8re d\u2019efficacit\u00e9 tout en garantissant une <strong>s\u00e9curit\u00e9 et une fiabilit\u00e9 maximales \u00e0 ses clients<\/strong>.  <\/p>\n<p>Gr\u00e2ce \u00e0 cette strat\u00e9gie d\u2019innovation, KERN s\u2019est impos\u00e9 comme un partenaire de confiance pour les entreprises de toutes tailles \u2013 de la PME au grand groupe international. La reconnaissance de Nimdzi vient confirmer de mani\u00e8re \u00e9clatante la trajectoire de croissance de l\u2019entreprise et son r\u00f4le en tant que partenaire mondialement reconnu pour une gestion linguistique sur mesure. <\/p>\n<p>Pour en savoir plus sur le classement Nimdzi, cliquez <a href=\"https:\/\/www.nimdzi.com\/nimdzi-100-2025\" data-cke-saved-href=\"https:\/\/www.nimdzi.com\/nimdzi-100-2025\">ici<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nimdzi confirme l\u2019innovation et la pertinence internationale : KERN se distingue par son excellence technologique, ses solutions sur mesure et sa vision tourn\u00e9e vers l\u2019avenir de la communication mondiale.<\/p>\n","protected":false},"author":7,"featured_media":29466,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[394],"tags":[395,396,397],"post_folder":[],"class_list":["post-29523","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-communiques-de-presse","tag-communiques-de-presse","tag-distinction","tag-nimdzi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KERN reconnu comme un leader mondial des services linguistiques - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KERN reconnu comme un leader mondial des services linguistiques - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"og:description\" content=\"Nimdzi confirme l\u2019innovation et la pertinence internationale : KERN se distingue par son excellence technologique, ses solutions sur mesure et sa vision tourn\u00e9e vers l\u2019avenir de la communication mondiale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-29T10:24:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-17T07:42:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Nimdzi-Top-75-2025.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Tao Nguyen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tao Nguyen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/\"},\"author\":{\"name\":\"Tao Nguyen\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#\\\/schema\\\/person\\\/16af75705a72e9bcf0f73788600aa58a\"},\"headline\":\"KERN reconnu comme un leader mondial des services linguistiques\",\"datePublished\":\"2025-04-29T10:24:00+00:00\",\"dateModified\":\"2026-02-17T07:42:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/\"},\"wordCount\":514,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Nimdzi-Top-75-2025.webp\",\"keywords\":[\"Communiqu\u00e9s de presse\",\"distinction\",\"Nimdzi\"],\"articleSection\":[\"Communiqu\u00e9s de presse\"],\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/\",\"name\":\"KERN reconnu comme un leader mondial des services linguistiques - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Nimdzi-Top-75-2025.webp\",\"datePublished\":\"2025-04-29T10:24:00+00:00\",\"dateModified\":\"2026-02-17T07:42:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Nimdzi-Top-75-2025.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Nimdzi-Top-75-2025.webp\",\"width\":1024,\"height\":768,\"caption\":\"Nimdzi confirme l\u2019innovation et la pertinence internationale : KERN se distingue par son excellence technologique, ses solutions sur mesure et sa vision tourn\u00e9e vers l\u2019avenir de la communication mondiale.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KERN reconnu comme un leader mondial des services linguistiques\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/fr\\\/#\\\/schema\\\/person\\\/16af75705a72e9bcf0f73788600aa58a\",\"name\":\"Tao Nguyen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"caption\":\"Tao Nguyen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KERN reconnu comme un leader mondial des services linguistiques - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/","og_locale":"fr_FR","og_type":"article","og_title":"KERN reconnu comme un leader mondial des services linguistiques - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","og_description":"Nimdzi confirme l\u2019innovation et la pertinence internationale : KERN se distingue par son excellence technologique, ses solutions sur mesure et sa vision tourn\u00e9e vers l\u2019avenir de la communication mondiale.","og_url":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_published_time":"2025-04-29T10:24:00+00:00","article_modified_time":"2026-02-17T07:42:35+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Nimdzi-Top-75-2025.webp","type":"image\/webp"}],"author":"Tao Nguyen","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Tao Nguyen","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#article","isPartOf":{"@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/"},"author":{"name":"Tao Nguyen","@id":"https:\/\/www.e-kern.com\/fr\/#\/schema\/person\/16af75705a72e9bcf0f73788600aa58a"},"headline":"KERN reconnu comme un leader mondial des services linguistiques","datePublished":"2025-04-29T10:24:00+00:00","dateModified":"2026-02-17T07:42:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/"},"wordCount":514,"commentCount":0,"publisher":{"@id":"https:\/\/www.e-kern.com\/fr\/#organization"},"image":{"@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Nimdzi-Top-75-2025.webp","keywords":["Communiqu\u00e9s de presse","distinction","Nimdzi"],"articleSection":["Communiqu\u00e9s de presse"],"inLanguage":"fr-FR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/","url":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/","name":"KERN reconnu comme un leader mondial des services linguistiques - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","isPartOf":{"@id":"https:\/\/www.e-kern.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Nimdzi-Top-75-2025.webp","datePublished":"2025-04-29T10:24:00+00:00","dateModified":"2026-02-17T07:42:35+00:00","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Nimdzi-Top-75-2025.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Nimdzi-Top-75-2025.webp","width":1024,"height":768,"caption":"Nimdzi confirme l\u2019innovation et la pertinence internationale : KERN se distingue par son excellence technologique, ses solutions sur mesure et sa vision tourn\u00e9e vers l\u2019avenir de la communication mondiale."},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/fr\/kern-reconnu-comme-un-leader-mondial-des-services-linguistiques\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.e-kern.com\/fr\/"},{"@type":"ListItem","position":2,"name":"KERN reconnu comme un leader mondial des services linguistiques"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/fr\/#website","url":"https:\/\/www.e-kern.com\/fr\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/fr\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.e-kern.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]},{"@type":"Person","@id":"https:\/\/www.e-kern.com\/fr\/#\/schema\/person\/16af75705a72e9bcf0f73788600aa58a","name":"Tao Nguyen","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","caption":"Tao Nguyen"}}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/posts\/29523","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/comments?post=29523"}],"version-history":[{"count":1,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/posts\/29523\/revisions"}],"predecessor-version":[{"id":29524,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/posts\/29523\/revisions\/29524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/media\/29466"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/media?parent=29523"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/categories?post=29523"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/tags?post=29523"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/fr\/wp-json\/wp\/v2\/post_folder?post=29523"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}