{"id":8135,"date":"2023-05-26T14:45:44","date_gmt":"2023-05-26T12:45:44","guid":{"rendered":"https:\/\/www.e-kern.com\/die-kern-ag-erzielt-positives-assessment-ergebnis\/"},"modified":"2026-03-23T13:47:05","modified_gmt":"2026-03-23T12:47:05","slug":"die-kern-ag-erzielt-positives-assessment-ergebnis","status":"publish","type":"post","link":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/","title":{"rendered":"Die KERN AG erzielt positives Assessment-Ergebnis"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8135\" class=\"elementor elementor-8135 elementor-2934\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea232a9 e-flex e-con-boxed e-con e-parent\" data-id=\"ea232a9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ac7f99 elementor-widget elementor-widget-text-editor\" data-id=\"7ac7f99\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die KERN AG, Sprachendienste freut sich bekannt zu geben, dass sie ein positives Assessment-Ergebnis bei der Compliance-Plattform IntegrityNext, die von namhaften gro\u00dfen Unternehmen genutzt wird, erreicht hat. Diese Auszeichnung best\u00e4tigt das Engagement der KERN AG f\u00fcr ethische Gesch\u00e4ftspraktiken und Nachhaltigkeit in der Lieferkette.<\/p><blockquote><p>&#8220;Uns erfreut das positives Assessment-Ergebnis bei IntegrityNext&#8221;, sagte Dr. Thomas Kern, Gesch\u00e4ftsf\u00fchrer der KERN AG. &#8220;Es ist ein Beleg f\u00fcr unsere kontinuierlichen Bem\u00fchungen, h\u00f6chste ethische Standards und Nachhaltigkeit in unserer gesamten Lieferkette zu gew\u00e4hrleisten. Bei der KERN AG sind wir davon \u00fcberzeugt, dass verantwortungsbewusstes Handeln der Schl\u00fcssel zu langfristigem Erfolg ist und wir werden weiterhin daran arbeiten, diese Werte in unserer t\u00e4glichen Gesch\u00e4ftst\u00e4tigkeit zu verankern.&#8221;<\/p><\/blockquote><p>Die KERN AG hat sich stets der F\u00f6rderung von Transparenz und Integrit\u00e4t verschrieben. Das positive Ergebnis bei IntegrityNext best\u00e4tigt nicht nur das Engagement der KERN AG f\u00fcr Compliance und Nachhaltigkeit, sondern unterstreicht auch die Wettbewerbsf\u00e4higkeit des Unternehmens auf dem Markt. Die Kunden der KERN AG, Sprachendienste k\u00f6nnen sich darauf verlassen, dass das Unternehmen ihre Anforderungen erf\u00fcllt und h\u00f6chste Standards bei ethischen Gesch\u00e4ftspraktiken und Nachhaltigkeit einh\u00e4lt.<\/p><p>IntegrityNext ist eine Plattform, die Unternehmen dabei unterst\u00fctzt, die Einhaltung von Compliance-Anforderungen entlang ihrer globalen Lieferkette zu gew\u00e4hrleisten. Sie erm\u00f6glicht es Unternehmen, potenzielle Risiken zu identifizieren, Compliance-Verst\u00f6\u00dfe aufzudecken und die Nachhaltigkeitsleistung ihrer Lieferanten zu bewerten. Die KERN AG hat bei IntegrityNext die f\u00fcr sich als Sprachdienstleister besonders wichtigen Kategorien Umweltschutz, Menschen- und Arbeitsrechte, Qualit\u00e4tsmanagement und Cyber-Sicherheit identifiziert.<\/p><p>\u00a0<\/p><p><a href=\"https:\/\/app.integritynext.com\/profiles\/df2da8c1-d97d-4544-b1b2-a117ea915b52\">Hier<\/a> geht es zum Sustainability Profil der KERN AG auf IntegrityNext.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Auszeichnung best\u00e4tigt das Engagement der KERN AG, Sprachendienste f\u00fcr ethische Gesch\u00e4ftspraktiken und Nachhaltigkeit in der Lieferkette.<\/p>\n","protected":false},"author":9,"featured_media":8136,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[89],"tags":[],"post_folder":[],"class_list":["post-8135","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presse"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die KERN AG erzielt positives Assessment-Ergebnis - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die KERN AG erzielt positives Assessment-Ergebnis - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"og:description\" content=\"Auszeichnung best\u00e4tigt das Engagement der KERN AG, Sprachendienste f\u00fcr ethische Gesch\u00e4ftspraktiken und Nachhaltigkeit in der Lieferkette.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-05-26T12:45:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T12:47:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Assessment-Ergebnis-2023.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Maria Ion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Maria Ion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/\"},\"author\":{\"name\":\"Maria Ion\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/person\\\/497a2c05ab87df0922ea365e1ba19d67\"},\"headline\":\"Die KERN AG erzielt positives Assessment-Ergebnis\",\"datePublished\":\"2023-05-26T12:45:44+00:00\",\"dateModified\":\"2026-03-23T12:47:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/\"},\"wordCount\":277,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Assessment-Ergebnis-2023.webp\",\"articleSection\":[\"Presse\"],\"inLanguage\":\"CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/\",\"name\":\"Die KERN AG erzielt positives Assessment-Ergebnis - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Assessment-Ergebnis-2023.webp\",\"datePublished\":\"2023-05-26T12:45:44+00:00\",\"dateModified\":\"2026-03-23T12:47:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#breadcrumb\"},\"inLanguage\":\"CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"CH\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Assessment-Ergebnis-2023.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/Assessment-Ergebnis-2023.webp\",\"width\":1024,\"height\":768,\"caption\":\"Die KERN AG erzielt positives Assessment-Ergebnis\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/die-kern-ag-erzielt-positives-assessment-ergebnis\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die KERN AG erzielt positives Assessment-Ergebnis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"CH\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/person\\\/497a2c05ab87df0922ea365e1ba19d67\",\"name\":\"Maria Ion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b35ace3824309552ae88d4a776042fb0c520826dc264267b5fb67a9a992a06cb?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b35ace3824309552ae88d4a776042fb0c520826dc264267b5fb67a9a992a06cb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/b35ace3824309552ae88d4a776042fb0c520826dc264267b5fb67a9a992a06cb?s=96&d=mm&r=g\",\"caption\":\"Maria Ion\"},\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/author\\\/mariai\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die KERN AG erzielt positives Assessment-Ergebnis - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/","og_locale":"en_US","og_type":"article","og_title":"Die KERN AG erzielt positives Assessment-Ergebnis - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","og_description":"Auszeichnung best\u00e4tigt das Engagement der KERN AG, Sprachendienste f\u00fcr ethische Gesch\u00e4ftspraktiken und Nachhaltigkeit in der Lieferkette.","og_url":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_published_time":"2023-05-26T12:45:44+00:00","article_modified_time":"2026-03-23T12:47:05+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Assessment-Ergebnis-2023.webp","type":"image\/webp"}],"author":"Maria Ion","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Maria Ion","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#article","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/"},"author":{"name":"Maria Ion","@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/person\/497a2c05ab87df0922ea365e1ba19d67"},"headline":"Die KERN AG erzielt positives Assessment-Ergebnis","datePublished":"2023-05-26T12:45:44+00:00","dateModified":"2026-03-23T12:47:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/"},"wordCount":277,"commentCount":0,"publisher":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#organization"},"image":{"@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Assessment-Ergebnis-2023.webp","articleSection":["Presse"],"inLanguage":"CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/","url":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/","name":"Die KERN AG erzielt positives Assessment-Ergebnis - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Assessment-Ergebnis-2023.webp","datePublished":"2023-05-26T12:45:44+00:00","dateModified":"2026-03-23T12:47:05+00:00","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#breadcrumb"},"inLanguage":"CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/"]}]},{"@type":"ImageObject","inLanguage":"CH","@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Assessment-Ergebnis-2023.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/Assessment-Ergebnis-2023.webp","width":1024,"height":768,"caption":"Die KERN AG erzielt positives Assessment-Ergebnis"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/de-ch\/die-kern-ag-erzielt-positives-assessment-ergebnis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.e-kern.com\/de-ch\/"},{"@type":"ListItem","position":2,"name":"Die KERN AG erzielt positives Assessment-Ergebnis"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/de-ch\/#website","url":"https:\/\/www.e-kern.com\/de-ch\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/de-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"CH"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/de-ch\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/de-ch\/","logo":{"@type":"ImageObject","inLanguage":"CH","@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]},{"@type":"Person","@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/person\/497a2c05ab87df0922ea365e1ba19d67","name":"Maria Ion","image":{"@type":"ImageObject","inLanguage":"CH","@id":"https:\/\/secure.gravatar.com\/avatar\/b35ace3824309552ae88d4a776042fb0c520826dc264267b5fb67a9a992a06cb?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/b35ace3824309552ae88d4a776042fb0c520826dc264267b5fb67a9a992a06cb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b35ace3824309552ae88d4a776042fb0c520826dc264267b5fb67a9a992a06cb?s=96&d=mm&r=g","caption":"Maria Ion"},"url":"https:\/\/www.e-kern.com\/de-ch\/author\/mariai\/"}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts\/8135","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/comments?post=8135"}],"version-history":[{"count":1,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts\/8135\/revisions"}],"predecessor-version":[{"id":11318,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts\/8135\/revisions\/11318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/media\/8136"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/media?parent=8135"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/categories?post=8135"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/tags?post=8135"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/post_folder?post=8135"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}