{"id":8053,"date":"2024-11-05T10:50:00","date_gmt":"2024-11-05T09:50:00","guid":{"rendered":"https:\/\/www.e-kern.com\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/"},"modified":"2026-03-23T13:43:44","modified_gmt":"2026-03-23T12:43:44","slug":"kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement","status":"publish","type":"post","link":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/","title":{"rendered":"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8053\" class=\"elementor elementor-8053 elementor-2417\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db3d145 e-con-full e-flex e-con e-parent\" data-id=\"db3d145\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b998e90 elementor-widget elementor-widget-text-editor\" data-id=\"b998e90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Frankfurt am Main \u2013 Die KERN AG, Sprachendienste, freut sich, bekannt zu geben, dass sie in ihrer diesj\u00e4hrigen Bewertung durch EcoVadis, dem globalen Standard f\u00fcr Nachhaltigkeitsratings, mit der Bronze-Medaille ausgezeichnet wurde. Die erneute Auszeichnung best\u00e4tigt das kontinuierliche Engagement der KERN AG f\u00fcr verantwortungsbewusste Gesch\u00e4ftspraktiken und nachhaltiges Management und platziert das Unternehmen unter den besten 35% der weltweit bewerteten Firmen in allen Branchen.<\/p><p>Die EcoVadis-Auszeichnung ist eine weltweit anerkannte Bewertung, die die Nachhaltigkeitsleistung von Unternehmen in den Bereichen Umwelt, Arbeits- und Menschenrechte, Ethik sowie nachhaltige Beschaffung misst und bereits mehr als 130.000 Unternehmen bewertet hat. Die KERN AG hat in allen Kategorien ein starkes Managementsystem nachgewiesen und damit ihr Engagement f\u00fcr Nachhaltigkeit und soziale Verantwortung bekr\u00e4ftigt. Die EcoVadis Bronze-Medaille best\u00e4tigt, dass die KERN AG die hohen Standards der EcoVadis-Methodik erfolgreich erf\u00fcllt.<\/p><blockquote><p>\u201eDiese Auszeichnung ist eine Anerkennung f\u00fcr unsere kontinuierliche Arbeit im Bereich der Nachhaltigkeit. Sie zeigt, dass wir uns unserer Verantwortung gegen\u00fcber Umwelt und Gesellschaft bewusst sind und aktiv Ma\u00dfnahmen ergreifen, um unsere Gesch\u00e4ftspraktiken nachhaltiger und verantwortungsvoller zu gestalten,\u201c sagt Dr. Thomas Kern, Gesch\u00e4ftsf\u00fchrer der KERN AG. \u201eAls weltweit t\u00e4tiges Unternehmen sehen wir es als unsere Pflicht an, ein Vorbild zu sein und kontinuierlich an der Verbesserung unserer Nachhaltigkeitsstrategie zu arbeiten. Wir sind stolz darauf, einen Beitrag zu einer nachhaltigeren Zukunft leisten zu k\u00f6nnen und werden diesen Weg entschlossen weitergehen.\u201c<\/p><\/blockquote><p>Mit der EcoVadis-Bewertung verfolgt die KERN AG das Ziel, Nachhaltigkeit fest in alle Unternehmensbereiche zu integrieren und sicherzustellen, dass soziale und \u00f6kologische Standards in der gesamten Wertsch\u00f6pfungskette ber\u00fccksichtigt werden. Durch die konsequente Einhaltung und Weiterentwicklung dieser Standards gew\u00e4hrleistet die KERN AG, dass ihre Dienstleistungen nicht nur qualitativ hochwertig, sondern auch ethisch und \u00f6kologisch verantwortungsvoll sind. Diese Bronze-Auszeichnung ist ein sichtbares Zeichen f\u00fcr das Engagement, das das Unternehmen Tag f\u00fcr Tag lebt und weiter vorantreibt.\u00a0<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ein starkes Zeichen f\u00fcr herausragendes Engagement in nachhaltigem Management und verantwortungsbewussten Gesch\u00e4ftspraktiken.<\/p>\n","protected":false},"author":7,"featured_media":8054,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[89],"tags":[148,149,96,150],"post_folder":[],"class_list":["post-8053","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-presse","tag-bronze","tag-ecovadis","tag-pressemitteilung","tag-sociale-verantwortung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"og:description\" content=\"Ein starkes Zeichen f\u00fcr herausragendes Engagement in nachhaltigem Management und verantwortungsbewussten Gesch\u00e4ftspraktiken.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-05T09:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T12:43:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/ecovadis-Auszeichnung-2024.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Tao Nguyen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tao Nguyen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/\"},\"author\":{\"name\":\"Tao Nguyen\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/person\\\/16af75705a72e9bcf0f73788600aa58a\"},\"headline\":\"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement\",\"datePublished\":\"2024-11-05T09:50:00+00:00\",\"dateModified\":\"2026-03-23T12:43:44+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/\"},\"wordCount\":323,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ecovadis-Auszeichnung-2024.webp\",\"keywords\":[\"bronze\",\"ecovadis\",\"Pressemitteilung\",\"sociale verantwortung\"],\"articleSection\":[\"Presse\"],\"inLanguage\":\"CH\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/\",\"name\":\"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ecovadis-Auszeichnung-2024.webp\",\"datePublished\":\"2024-11-05T09:50:00+00:00\",\"dateModified\":\"2026-03-23T12:43:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#breadcrumb\"},\"inLanguage\":\"CH\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"CH\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ecovadis-Auszeichnung-2024.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/ecovadis-Auszeichnung-2024.webp\",\"width\":1024,\"height\":768,\"caption\":\"Abzeichen f\u00fcr EcoVadis Bronze\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"CH\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"CH\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/#\\\/schema\\\/person\\\/16af75705a72e9bcf0f73788600aa58a\",\"name\":\"Tao Nguyen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"CH\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"caption\":\"Tao Nguyen\"},\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-ch\\\/author\\\/taon\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/","og_locale":"en_US","og_type":"article","og_title":"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","og_description":"Ein starkes Zeichen f\u00fcr herausragendes Engagement in nachhaltigem Management und verantwortungsbewussten Gesch\u00e4ftspraktiken.","og_url":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_published_time":"2024-11-05T09:50:00+00:00","article_modified_time":"2026-03-23T12:43:44+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/ecovadis-Auszeichnung-2024.webp","type":"image\/webp"}],"author":"Tao Nguyen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tao Nguyen","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#article","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/"},"author":{"name":"Tao Nguyen","@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/person\/16af75705a72e9bcf0f73788600aa58a"},"headline":"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement","datePublished":"2024-11-05T09:50:00+00:00","dateModified":"2026-03-23T12:43:44+00:00","mainEntityOfPage":{"@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/"},"wordCount":323,"commentCount":0,"publisher":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#organization"},"image":{"@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/ecovadis-Auszeichnung-2024.webp","keywords":["bronze","ecovadis","Pressemitteilung","sociale verantwortung"],"articleSection":["Presse"],"inLanguage":"CH","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/","url":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/","name":"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/ecovadis-Auszeichnung-2024.webp","datePublished":"2024-11-05T09:50:00+00:00","dateModified":"2026-03-23T12:43:44+00:00","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#breadcrumb"},"inLanguage":"CH","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/"]}]},{"@type":"ImageObject","inLanguage":"CH","@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/ecovadis-Auszeichnung-2024.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/ecovadis-Auszeichnung-2024.webp","width":1024,"height":768,"caption":"Abzeichen f\u00fcr EcoVadis Bronze"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/de-ch\/kern-ag-sprachendienste-erhaelt-ecovadis-bronze-medaille-fuer-nachhaltiges-engagement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.e-kern.com\/de-ch\/"},{"@type":"ListItem","position":2,"name":"KERN AG, Sprachendienste erh\u00e4lt EcoVadis Bronze-Medaille f\u00fcr nachhaltiges Engagement"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/de-ch\/#website","url":"https:\/\/www.e-kern.com\/de-ch\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/de-ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"CH"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/de-ch\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/de-ch\/","logo":{"@type":"ImageObject","inLanguage":"CH","@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]},{"@type":"Person","@id":"https:\/\/www.e-kern.com\/de-ch\/#\/schema\/person\/16af75705a72e9bcf0f73788600aa58a","name":"Tao Nguyen","image":{"@type":"ImageObject","inLanguage":"CH","@id":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","caption":"Tao Nguyen"},"url":"https:\/\/www.e-kern.com\/de-ch\/author\/taon\/"}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts\/8053","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/comments?post=8053"}],"version-history":[{"count":1,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts\/8053\/revisions"}],"predecessor-version":[{"id":11296,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/posts\/8053\/revisions\/11296"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/media\/8054"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/media?parent=8053"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/categories?post=8053"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/tags?post=8053"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-ch\/wp-json\/wp\/v2\/post_folder?post=8053"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}