{"id":8103,"date":"2023-11-01T16:43:00","date_gmt":"2023-11-01T15:43:00","guid":{"rendered":"https:\/\/www.e-kern.com\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/"},"modified":"2026-03-23T13:51:04","modified_gmt":"2026-03-23T12:51:04","slug":"kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten","status":"publish","type":"post","link":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/","title":{"rendered":"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8103\" class=\"elementor elementor-8103 elementor-2973\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c17fd0a e-flex e-con-boxed e-con e-parent\" data-id=\"c17fd0a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6f966ef elementor-widget elementor-widget-text-editor\" data-id=\"6f966ef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die KERN Group, die 1969 als Familienunternehmen in Frankfurt am Main gegr\u00fcndet wurde, kann auf eine lange Geschichte zur\u00fcckblicken. Damit ist sie nicht nur ein Symbol f\u00fcr sprachliche Expertise, sondern auch f\u00fcr internationale Reichweite. Mit \u00fcber 60 Standorten weltweit demonstriert sie ihre Position als f\u00fchrender Full-Service-Spezialist f\u00fcr fremdsprachliche Kommunikation.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-78384b5 elementor-widget elementor-widget-image\" data-id=\"78384b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"800\" height=\"686\" src=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp\" class=\"attachment-large size-large wp-image-8104\" alt=\"KERN Jubil\u00e4en, Niederlassungen\" srcset=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp 1024w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-300x257.webp 300w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-768x659.webp 768w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen.webp 1200w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0d5b491 elementor-widget elementor-widget-text-editor\" data-id=\"0d5b491\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Im Jahr 2023 feiert die KERN Group eine beeindruckende Liste von Jubil\u00e4en:<\/p><ul><li><strong>40 Jahre<\/strong> &#8211; K\u00f6ln, M\u00fcnchen und Paris<\/li><li><strong>35 Jahre<\/strong> &#8211; London<\/li><li><strong>30 Jahre<\/strong> &#8211; Amsterdam, Dortmund, Kassel, Mainz und Saarbr\u00fccken<\/li><li><strong>25 Jahre<\/strong> &#8211; Darmstadt und Duisburg<\/li><li><strong>15 Jahre<\/strong> &#8211; Freiburg<\/li><li><strong>10 Jahre<\/strong> &#8211; Regensburg und Salzburg<\/li><\/ul><p>Jeder dieser Standorte hat seit seiner Gr\u00fcndung kontinuierlich zur Erfolgsgeschichte der KERN Group beigetragen. Die weltweiten Standorte bieten nicht nur kleinen und mittelst\u00e4ndischen Unternehmen, sondern auch internationalen Konzernen einen direkten Ansprechpartner vor Ort. Dies hat nicht nur die lokalen, sondern auch die internationalen Kundenbeziehungen erheblich vertieft und gest\u00e4rkt.<\/p><blockquote><p>\u201eDie Jubil\u00e4en dieser Standorte sind nicht nur ein Zeichen der Langlebigkeit, sondern auch der Qualit\u00e4t unserer Dienstleistungen und der Hingabe unseres Teams. Wir sind stolz darauf, unsere Kunden und Kundinnen in so vielen St\u00e4dten direkt betreuen zu k\u00f6nnen und freuen uns auf viele weitere Jahre erfolgreicher Zusammenarbeit. Unsere Pr\u00e4senz in den verschiedensten St\u00e4dten weltweit steht f\u00fcr Internationalit\u00e4t, Vertrauen und vor allem f\u00fcr unsere Kundenn\u00e4he\u201c, kommentiert Dr. Thomas Kern, Mitglied der Gesch\u00e4ftsf\u00fchrung der KERN Group.<\/p><\/blockquote><p>W\u00e4hrend die KERN Group auf eine Vielzahl an erreichten Meilensteinen zur\u00fcckblicken kann, bleibt sie zugleich motiviert, den Weg der Innovation und Internationalit\u00e4t fortzusetzen und die Weiterentwicklung von Technologien und erstklassigen Sprachendienste voranzutreiben, um ihre Kunden und Kundinnen mit ma\u00dfgeschneiderten L\u00f6sungen in der internationalen Kommunikation zu unterst\u00fctzen und \u00dcbersetzungsprojekte noch effizienter zu gestalten.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ein Jahr voller Feierlichkeiten f\u00fcr die KERN Group! Zahlreiche Filialen in ganz Europa feiern in diesem Jahr ihr Jubil\u00e4um. Ein Beweis f\u00fcr die nachhaltige Pr\u00e4senz, anhaltende Qualit\u00e4t und stetiger innovativer Weiterentwicklungen der globalen Sprachendienste in Europa.<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[87],"tags":[155,156],"post_folder":[],"class_list":["post-8103","post","type-post","status-publish","format-standard","hentry","category-presse","tag-kern-jubilaeen","tag-niederlassungen-nach-jahren"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"og:description\" content=\"Ein Jahr voller Feierlichkeiten f\u00fcr die KERN Group! Zahlreiche Filialen in ganz Europa feiern in diesem Jahr ihr Jubil\u00e4um. Ein Beweis f\u00fcr die nachhaltige Pr\u00e4senz, anhaltende Qualit\u00e4t und stetiger innovativer Weiterentwicklungen der globalen Sprachendienste in Europa.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-01T15:43:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T12:51:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp\" \/>\n<meta name=\"author\" content=\"Christian Fanta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fanta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/\"},\"author\":{\"name\":\"Christian Fanta\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/person\\\/aee435c139bf247de57c3cec27c414a6\"},\"headline\":\"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten\",\"datePublished\":\"2023-11-01T15:43:00+00:00\",\"dateModified\":\"2026-03-23T12:51:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/\"},\"wordCount\":304,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/KERN-Jubilaeen-1024x878.webp\",\"keywords\":[\"KERN Jubil\u00e4en\",\"Niederlassungen nach Jahren\"],\"articleSection\":[\"Presse\"],\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/\",\"name\":\"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/KERN-Jubilaeen-1024x878.webp\",\"datePublished\":\"2023-11-01T15:43:00+00:00\",\"dateModified\":\"2026-03-23T12:51:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#breadcrumb\"},\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/KERN-Jubilaeen-1024x878.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/KERN-Jubilaeen-1024x878.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/person\\\/aee435c139bf247de57c3cec27c414a6\",\"name\":\"Christian Fanta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g\",\"caption\":\"Christian Fanta\"},\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/author\\\/christianf\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/","og_locale":"en_US","og_type":"article","og_title":"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","og_description":"Ein Jahr voller Feierlichkeiten f\u00fcr die KERN Group! Zahlreiche Filialen in ganz Europa feiern in diesem Jahr ihr Jubil\u00e4um. Ein Beweis f\u00fcr die nachhaltige Pr\u00e4senz, anhaltende Qualit\u00e4t und stetiger innovativer Weiterentwicklungen der globalen Sprachendienste in Europa.","og_url":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_published_time":"2023-11-01T15:43:00+00:00","article_modified_time":"2026-03-23T12:51:04+00:00","og_image":[{"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp","type":"","width":"","height":""}],"author":"Christian Fanta","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christian Fanta","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#article","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/"},"author":{"name":"Christian Fanta","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/person\/aee435c139bf247de57c3cec27c414a6"},"headline":"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten","datePublished":"2023-11-01T15:43:00+00:00","dateModified":"2026-03-23T12:51:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/"},"wordCount":304,"commentCount":0,"publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp","keywords":["KERN Jubil\u00e4en","Niederlassungen nach Jahren"],"articleSection":["Presse"],"inLanguage":"AT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/","url":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/","name":"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp","datePublished":"2023-11-01T15:43:00+00:00","dateModified":"2026-03-23T12:51:04+00:00","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#breadcrumb"},"inLanguage":"AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/"]}]},{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/KERN-Jubilaeen-1024x878.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/de-at\/kern-group-feiert-jubilaeen-in-zahlreichen-europaeischen-staedten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.e-kern.com\/de-at\/startseite\/"},{"@type":"ListItem","position":2,"name":"KERN Group feiert Jubil\u00e4en in zahlreichen europ\u00e4ischen St\u00e4dten"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/de-at\/#website","url":"https:\/\/www.e-kern.com\/de-at\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/de-at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"AT"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/de-at\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/de-at\/","logo":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]},{"@type":"Person","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/person\/aee435c139bf247de57c3cec27c414a6","name":"Christian Fanta","image":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/secure.gravatar.com\/avatar\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g","caption":"Christian Fanta"},"url":"https:\/\/www.e-kern.com\/de-at\/author\/christianf\/"}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/8103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/comments?post=8103"}],"version-history":[{"count":1,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/8103\/revisions"}],"predecessor-version":[{"id":10934,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/8103\/revisions\/10934"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media?parent=8103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/categories?post=8103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/tags?post=8103"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/post_folder?post=8103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}