{"id":8011,"date":"2025-07-21T10:55:19","date_gmt":"2025-07-21T08:55:19","guid":{"rendered":"https:\/\/www.e-kern.com\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/"},"modified":"2026-03-23T13:39:35","modified_gmt":"2026-03-23T12:39:35","slug":"kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband","status":"publish","type":"post","link":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/","title":{"rendered":"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"8011\" class=\"elementor elementor-8011 elementor-2158\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a91869d e-flex e-con-boxed e-con e-parent\" data-id=\"a91869d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c6448f5 elementor-widget elementor-widget-text-editor\" data-id=\"c6448f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>KERN Global Language Services, einer der f\u00fchrenden Anbieter f\u00fcr globales Sprachenmanagement, ist ab sofort gelisteter Sprachdienstleister f\u00fcr DIRK (Deutscher Investor Relations Verband). Als Partner des gr\u00f6\u00dften europ\u00e4ischen Zusammenschlusses f\u00fcr Investor Relations unterstreicht KERN damit sein Engagement f\u00fcr h\u00f6chste Qualit\u00e4t und Branchenn\u00e4he in der Finanzkommunikation.<\/p><p>Mit dem dedizierten <strong>Kompetenzzentrum f\u00fcr Finanzen<\/strong> bietet KERN Global Language Services spezialisierte Sprachdienstleistungen f\u00fcr die komplexe Kapitalmarktkommunikation. Erfahrene ProjektmanagerInnen mit Branchen-Know-how und zertifizierte Fach\u00fcbersetzerInnen gew\u00e4hrleisten eine konsistente, passgenaue Adaption der Inhalte in die gew\u00fcnschten Zielsprachen \u2013 von der ersten Abstimmung bis zur finalen Qualit\u00e4tskontrolle. Zum Leistungsportfolio z\u00e4hlen unter anderem <a href=\"https:\/\/www.e-kern.com\/de\/uebersetzen\/geschaeftsbericht-uebersetzen\/\">\u00dcbersetzungen von Gesch\u00e4fts- und Finanzberichten<\/a>, ESG-konforme Inhalte, fremdsprachiges <a href=\"https:\/\/www.e-kern.com\/de\/services\/dtp-druck\/\">Desktop-Publishing<\/a> inklusive Druckabwicklung sowie professionelles <a href=\"https:\/\/www.e-kern.com\/de\/services\/dolmetschen\/\">Dolmetschen<\/a> f\u00fcr Konferenzen, Hauptversammlungen und Meetings. Ob pr\u00e4zise Finanzterminologie oder stilistisch \u00fcberzeugende Texte: KERN Global Language Services sorgt f\u00fcr konsistente, passgenaue Adaption in der Zielsprache.<\/p><p>Was KERN auszeichnet, ist die Verbindung sprachlicher Exzellenz mit finanzspezifischer Kompetenz: IR-erfahrenes Projektmanagement, ein flexibles Netzwerk zertifizierter \u00dcbersetzerinnen und \u00dcbersetzer, der gezielte Aufbau und die Pflege finanzspezifischer Terminologiedatenbanken (z.\u202fB. IFRS, ESRS, HGB) sowie die nahtlose Integration in Reporting- und Disclosure-Prozesse. KERN arbeitet routiniert mit allen g\u00e4ngigen Dateiformaten und Systemen \u2013 darunter u. a. Workiva, SAP, Firesys und SmartNotes.<\/p><p>So unterst\u00fctzt KERN Unternehmen dabei, ihre Botschaften klar und konsistent in internationalen M\u00e4rkten zu positionieren. Dank umfassender regulatorischer Expertise und zertifizierter Qualit\u00e4tssicherung erf\u00fcllt KERN die hohen Anforderungen b\u00f6rsennotierter Unternehmen und Finanzdienstleister.<\/p><p>\u201eProfessionelle Sprachdienstleistungen sind ein integraler Bestandteil erfolgreicher Finanzkommunikation \u2013 ob in regulatorisch relevanten Dokumenten, Investor Updates oder mehrsprachigen ESG-Berichten\u201c, erkl\u00e4rt Dr. Thomas Kern, Vorstand der KERN Global Language Services. \u201eMit unserem Kompetenzzentrum f\u00fcr Finanzen bieten wir eine spezialisierte L\u00f6sung, die exakt auf die Anforderungen von Finanzdienstleistern, Emittenten und IR-Abteilungen zugeschnitten ist. Unsere St\u00e4rke liegt in der Verbindung von branchenerfahrener Fach\u00fcbersetzung in allen Weltsprachen und ISO-zertifizierter Qualit\u00e4t. So stellen wir sicher, dass Finanzinhalte weltweit konsistent, regelkonform und sprachlich pr\u00e4zise kommuniziert werden. Als gelisteter Sprachdienstleister f\u00fcr DIRK sehen wir es als unsere Aufgabe, die IR-Community mit zuverl\u00e4ssigen, skalierbaren und technologisch f\u00fchrenden L\u00f6sungen im globalen Sprachenmanagement zu unterst\u00fctzen \u2013 f\u00fcr eine Finanzkommunikation, die Vertrauen schafft, internationale M\u00e4rkte erreicht und den digitalen Anforderungen der Branche gewachsen ist.\u201c<\/p><p>KERN Global Language Services freut sich darauf, den Austausch im Verband aktiv mitzugestalten und ihre sprachliche Expertise in k\u00fcnftige Veranstaltungen, Fachgruppen und Weiterbildungsangebote des DIRK einzubringen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>St\u00e4rkung der Finanzkommunikation durch branchenspezifische Sprachdienstleistungen<\/p>\n","protected":false},"author":6,"featured_media":8012,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[97],"tags":[],"post_folder":[],"class_list":["post-8011","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"og:description\" content=\"St\u00e4rkung der Finanzkommunikation durch branchenspezifische Sprachdienstleistungen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-21T08:55:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T12:39:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/DIRK-KERN-Sprachdienstleister-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Christian Fanta\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Christian Fanta\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/\"},\"author\":{\"name\":\"Christian Fanta\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/person\\\/aee435c139bf247de57c3cec27c414a6\"},\"headline\":\"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband\",\"datePublished\":\"2025-07-21T08:55:19+00:00\",\"dateModified\":\"2026-03-23T12:39:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/\"},\"wordCount\":421,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DIRK-KERN-Sprachdienstleister-1.webp\",\"articleSection\":[\"News\"],\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/\",\"name\":\"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DIRK-KERN-Sprachdienstleister-1.webp\",\"datePublished\":\"2025-07-21T08:55:19+00:00\",\"dateModified\":\"2026-03-23T12:39:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#breadcrumb\"},\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DIRK-KERN-Sprachdienstleister-1.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/DIRK-KERN-Sprachdienstleister-1.webp\",\"width\":1024,\"height\":768,\"caption\":\"KERN ist Sprachdienstleister f\u00fcr DIRK\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/person\\\/aee435c139bf247de57c3cec27c414a6\",\"name\":\"Christian Fanta\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g\",\"caption\":\"Christian Fanta\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/","og_locale":"en_US","og_type":"article","og_title":"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","og_description":"St\u00e4rkung der Finanzkommunikation durch branchenspezifische Sprachdienstleistungen","og_url":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_published_time":"2025-07-21T08:55:19+00:00","article_modified_time":"2026-03-23T12:39:35+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/DIRK-KERN-Sprachdienstleister-1.webp","type":"image\/webp"}],"author":"Christian Fanta","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Christian Fanta","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#article","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/"},"author":{"name":"Christian Fanta","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/person\/aee435c139bf247de57c3cec27c414a6"},"headline":"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband","datePublished":"2025-07-21T08:55:19+00:00","dateModified":"2026-03-23T12:39:35+00:00","mainEntityOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/"},"wordCount":421,"commentCount":0,"publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/DIRK-KERN-Sprachdienstleister-1.webp","articleSection":["News"],"inLanguage":"AT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/","url":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/","name":"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/DIRK-KERN-Sprachdienstleister-1.webp","datePublished":"2025-07-21T08:55:19+00:00","dateModified":"2026-03-23T12:39:35+00:00","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#breadcrumb"},"inLanguage":"AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/"]}]},{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/DIRK-KERN-Sprachdienstleister-1.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/DIRK-KERN-Sprachdienstleister-1.webp","width":1024,"height":768,"caption":"KERN ist Sprachdienstleister f\u00fcr DIRK"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/de-at\/kern-global-language-services-ist-sprachdienstleister-fuer-dirk-deutscher-investor-relations-verband\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.e-kern.com\/de-at\/"},{"@type":"ListItem","position":2,"name":"KERN Global Language Services ist Sprachdienstleister f\u00fcr DIRK \u2013 Deutscher Investor Relations Verband"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/de-at\/#website","url":"https:\/\/www.e-kern.com\/de-at\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/de-at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"AT"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/de-at\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/de-at\/","logo":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]},{"@type":"Person","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/person\/aee435c139bf247de57c3cec27c414a6","name":"Christian Fanta","image":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/secure.gravatar.com\/avatar\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4c2ec6acb40e078d5d3c5dc67dada33840dde4d41b1a50def486c13254464a8d?s=96&d=mm&r=g","caption":"Christian Fanta"}}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/8011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/comments?post=8011"}],"version-history":[{"count":4,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/8011\/revisions"}],"predecessor-version":[{"id":37184,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/8011\/revisions\/37184"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media\/8012"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media?parent=8011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/categories?post=8011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/tags?post=8011"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/post_folder?post=8011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}