{"id":7999,"date":"2025-09-17T17:18:00","date_gmt":"2025-09-17T15:18:00","guid":{"rendered":"https:\/\/www.e-kern.com\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/"},"modified":"2026-03-23T13:35:46","modified_gmt":"2026-03-23T12:35:46","slug":"wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter","status":"publish","type":"post","link":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/","title":{"rendered":"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"7999\" class=\"elementor elementor-7999 elementor-2290\" data-elementor-post-type=\"post\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7886c3f e-flex e-con-boxed e-con e-parent\" data-id=\"7886c3f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-35aa02d elementor-widget elementor-widget-text-editor\" data-id=\"35aa02d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die Finanzwelt ist st\u00e4ndig in Bewegung. Neue Gesetze, angepasste Bilanzierungsmethoden und innovative Technologien ver\u00e4ndern die Anforderungen an die Unternehmensberichterstattung laufend. F\u00fcr uns als Sprachdienstleister ist es entscheidend, diese Entwicklungen nicht nur zu kennen, sondern im Detail zu verstehen. Nur so k\u00f6nnen wir die Finanz- und Nachhaltigkeitsberichte unserer Kunden pr\u00e4zise und kontextgerecht \u00fcbersetzen.<\/p><p>Die Teilnahme am PwC Expertenforum dient uns dazu, direkt am Puls des Marktes zu sein. Im Fokus stehen dabei zentrale Fragen, die auch unsere Kunden bewegen:<\/p><ul><li><strong>Trends &amp; Neuerungen:<\/strong> Welche aktuellen Entwicklungen gibt es in der Berichterstattung? Was \u00e4ndert sich im kommenden Berichtsjahr bei wichtigen Standards wie IFRS und HGB?<\/li><li><strong>Technologie:<\/strong> Welche neuen Tools und Plattformen setzen Unternehmen ein, mit denen auch wir uns als Dienstleister befassen m\u00fcssen?<\/li><li><strong>Marktverst\u00e4ndnis:<\/strong> Was sind die zentralen Herausforderungen f\u00fcr Unternehmen bei der Erstellung ihrer Gesch\u00e4fts- und Nachhaltigkeitsberichte?<\/li><\/ul><p>Das hier gewonnene Wissen flie\u00dft direkt in die Qualit\u00e4t unserer \u00dcbersetzungen ein. Wir verstehen die Hintergr\u00fcnde, kennen die Fachterminologie im Wandel und k\u00f6nnen so sicherstellen, dass Ihre Botschaft in jeder Sprache korrekt und wirkungsvoll ankommt.<\/p><p>Die Investition in die Weiterbildung unserer Fachexperten ist eine Investition in den Erfolg unserer Kunden.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Um unseren Kunden stets Fach\u00fcbersetzungen auf h\u00f6chstem Niveau zu bieten, ist kontinuierliche Weiterbildung f\u00fcr uns unerl\u00e4sslich. Daher nimmt eine Vertreterin der KERN AG am renommierten PwC Expertenforum \u201eUpdate zur Rechnungslegung und Berichterstattung\u201c teil.\u00a0<\/p>\n","protected":false},"author":7,"featured_media":8000,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"categories":[97],"tags":[88],"post_folder":[],"class_list":["post-7999","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"og:description\" content=\"Um unseren Kunden stets Fach\u00fcbersetzungen auf h\u00f6chstem Niveau zu bieten, ist kontinuierliche Weiterbildung f\u00fcr uns unerl\u00e4sslich. Daher nimmt eine Vertreterin der KERN AG am renommierten PwC Expertenforum \u201eUpdate zur Rechnungslegung und Berichterstattung\u201c teil.\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-17T15:18:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-23T12:35:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/09\/PwC-Expertenforum-2025.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"768\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Tao Nguyen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tao Nguyen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/\"},\"author\":{\"name\":\"Tao Nguyen\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/person\\\/16af75705a72e9bcf0f73788600aa58a\"},\"headline\":\"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter\",\"datePublished\":\"2025-09-17T15:18:00+00:00\",\"dateModified\":\"2026-03-23T12:35:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/\"},\"wordCount\":210,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PwC-Expertenforum-2025.webp\",\"keywords\":[\"News\"],\"articleSection\":[\"News\"],\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/\",\"name\":\"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PwC-Expertenforum-2025.webp\",\"datePublished\":\"2025-09-17T15:18:00+00:00\",\"dateModified\":\"2026-03-23T12:35:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#breadcrumb\"},\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PwC-Expertenforum-2025.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/09\\\/PwC-Expertenforum-2025.webp\",\"width\":1024,\"height\":768,\"caption\":\"KERN AG bildet sich beim Expertenforum weiter\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/person\\\/16af75705a72e9bcf0f73788600aa58a\",\"name\":\"Tao Nguyen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g\",\"caption\":\"Tao Nguyen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/","og_locale":"en_US","og_type":"article","og_title":"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","og_description":"Um unseren Kunden stets Fach\u00fcbersetzungen auf h\u00f6chstem Niveau zu bieten, ist kontinuierliche Weiterbildung f\u00fcr uns unerl\u00e4sslich. Daher nimmt eine Vertreterin der KERN AG am renommierten PwC Expertenforum \u201eUpdate zur Rechnungslegung und Berichterstattung\u201c teil.\u00a0","og_url":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_published_time":"2025-09-17T15:18:00+00:00","article_modified_time":"2026-03-23T12:35:46+00:00","og_image":[{"width":1024,"height":768,"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/09\/PwC-Expertenforum-2025.webp","type":"image\/webp"}],"author":"Tao Nguyen","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tao Nguyen","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#article","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/"},"author":{"name":"Tao Nguyen","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/person\/16af75705a72e9bcf0f73788600aa58a"},"headline":"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter","datePublished":"2025-09-17T15:18:00+00:00","dateModified":"2026-03-23T12:35:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/"},"wordCount":210,"commentCount":0,"publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/09\/PwC-Expertenforum-2025.webp","keywords":["News"],"articleSection":["News"],"inLanguage":"AT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/","url":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/","name":"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter - \u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/09\/PwC-Expertenforum-2025.webp","datePublished":"2025-09-17T15:18:00+00:00","dateModified":"2026-03-23T12:35:46+00:00","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#breadcrumb"},"inLanguage":"AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/"]}]},{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/09\/PwC-Expertenforum-2025.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/09\/PwC-Expertenforum-2025.webp","width":1024,"height":768,"caption":"KERN AG bildet sich beim Expertenforum weiter"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/de-at\/wissen-was-kunden-bewegt-kern-ag-bildet-sich-beim-pwc-expertenforum-weiter\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.e-kern.com\/de-at\/"},{"@type":"ListItem","position":2,"name":"Wissen, was Kunden bewegt: KERN AG bildet sich beim PwC Expertenforum weiter"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/de-at\/#website","url":"https:\/\/www.e-kern.com\/de-at\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/de-at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"AT"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/de-at\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/de-at\/","logo":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]},{"@type":"Person","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/person\/16af75705a72e9bcf0f73788600aa58a","name":"Tao Nguyen","image":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/34e5aa66e4a8912aa847bb683cc721b6f07f3404fb70253f5e6ac33ad00099d9?s=96&d=mm&r=g","caption":"Tao Nguyen"}}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/7999","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/comments?post=7999"}],"version-history":[{"count":1,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/7999\/revisions"}],"predecessor-version":[{"id":10908,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/posts\/7999\/revisions\/10908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media\/8000"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media?parent=7999"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/categories?post=7999"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/tags?post=7999"},{"taxonomy":"post_folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/post_folder?post=7999"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}