{"id":8518,"date":"2025-12-02T16:22:29","date_gmt":"2025-12-02T15:22:29","guid":{"rendered":"https:\/\/www.e-kern.com\/arbeitnehmerueberlassung\/"},"modified":"2026-05-20T15:19:50","modified_gmt":"2026-05-20T13:19:50","slug":"arbeitnehmerueberlassung","status":"publish","type":"page","link":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/","title":{"rendered":"Arbeitnehmer\u00fcberlassung"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"8518\" class=\"elementor elementor-8518 elementor-2152\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5668d62 e-con-full e-flex e-con e-parent\" data-id=\"5668d62\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-fdbd380 elementor-hidden-tablet elementor-hidden-mobile e-flex e-con-boxed e-con e-child\" data-id=\"fdbd380\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-f3e50cb e-con-full e-flex e-con e-child\" data-id=\"f3e50cb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fb00ede elementor-widget elementor-widget-heading\" data-id=\"fb00ede\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Arbeitnehmer\u00fcberlassung<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-035c141 elementor-widget elementor-widget-heading\" data-id=\"035c141\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">ExpertInnen f\u00fcr Ihr Unternehmen<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c4fdcc elementor-widget elementor-widget-text-editor\" data-id=\"9c4fdcc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir stellen Ihnen gerne technische RedakteurInnen, DolmetscherInnen und \u00dcbersetzerInnen zur Seite.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d680c89 elementor-widget elementor-widget-button\" data-id=\"d680c89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c9b3ca e-con-full e-flex e-con e-child\" data-id=\"1c9b3ca\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-15e2f9b e-con-full elementor-hidden-tablet elementor-hidden-mobile e-flex e-con e-child\" data-id=\"15e2f9b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;position&quot;:&quot;absolute&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-8832d10 e-con-full e-flex e-con e-child\" data-id=\"8832d10\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c5819a e-con-full e-flex e-con e-child\" data-id=\"4c5819a\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5b05a73 e-con-full e-flex e-con e-child\" data-id=\"5b05a73\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7a513ad e-con-full e-flex e-con e-child\" data-id=\"7a513ad\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-05287c4 e-con-full elementor-hidden-desktop elementor-hidden-laptop e-flex e-con e-child\" data-id=\"05287c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-bd23438 e-con-full e-flex e-con e-child\" data-id=\"bd23438\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-7c2bf98 e-con-full e-flex e-con e-child\" data-id=\"7c2bf98\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-82b0e08 e-con-full e-flex e-con e-child\" data-id=\"82b0e08\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bd39c28 e-con-full e-flex e-con e-child\" data-id=\"bd39c28\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e47c61b elementor-widget elementor-widget-image\" data-id=\"e47c61b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1920\" height=\"1080\" src=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp\" class=\"attachment-full size-full wp-image-8519\" alt=\"Gesch\u00e4ftstreffen im B\u00fcro mit Handschlag, symbolisiert Arbeitnehmer\u00fcberlassung von \u00dcbersetzern und Dolmetschern\" srcset=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp 1920w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher-300x169.webp 300w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher-1024x576.webp 1024w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher-768x432.webp 768w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher-1536x864.webp 1536w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-a5d511f elementor-hidden-desktop elementor-hidden-laptop e-flex e-con-boxed e-con e-child\" data-id=\"a5d511f\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-624f9c4 e-con-full e-flex e-con e-child\" data-id=\"624f9c4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-042a558 elementor-widget elementor-widget-heading\" data-id=\"042a558\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Arbeitnehmer\u00fcberlassung<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a0873b8 elementor-widget elementor-widget-heading\" data-id=\"a0873b8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">ExperInnen f\u00fcr Ihr Unternehmen<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ec673c9 elementor-widget elementor-widget-text-editor\" data-id=\"ec673c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir stellen Ihnen gerne technische RedakteurInnen, DolmetscherInnen und \u00dcbersetzerInnen zur Seite.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-08c1128 elementor-widget elementor-widget-button\" data-id=\"08c1128\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt anfragen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c97c311 e-flex e-con-boxed e-con e-parent\" data-id=\"c97c311\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-63b652c elementor-widget elementor-widget-breadcrumbs\" data-id=\"63b652c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.e-kern.com\/de-at\/\">Startseite<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f50fa2d e-flex e-con-boxed e-con e-parent\" data-id=\"f50fa2d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2bef751 e-con-full e-flex e-con e-child\" data-id=\"2bef751\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9388a49 e-con-full e-flex e-con e-child\" data-id=\"9388a49\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-175e455 elementor-widget elementor-widget-heading\" data-id=\"175e455\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Arbeitnehmer\u00ad\u00fcberlassung: \u00dcbersetzen und Dolmetschen<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3211956 elementor-widget elementor-widget-heading\" data-id=\"3211956\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Unsere Sprachprofis unterst\u00fctzen Sie mit Ihrer Expertise<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29bea81 elementor-widget elementor-widget-text-editor\" data-id=\"29bea81\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Sie sind auf der Suche nach technischen RedakteurInnen, <a href=\"https:\/\/www.e-kern.com\/de-at\/services\/dolmetschen\/\">DolmetscherInnen<\/a> oder <a href=\"https:\/\/www.e-kern.com\/de-at\/uebersetzen\/\">\u00dcbersetzerInnen<\/a>, die Sie bei Auftragsspitzen, zeitlichen Engp\u00e4ssen oder im Rahmen langfristiger Projekte zielorientiert unterst\u00fctzen k\u00f6nnen?<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-0b366e3 e-flex e-con-boxed e-con e-parent\" data-id=\"0b366e3\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-8118b02 e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"8118b02\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-90189a3 elementor-widget elementor-widget-image\" data-id=\"90189a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/fluesterdolmetschen.webp\" class=\"attachment-full size-full wp-image-11091\" alt=\"\" srcset=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/fluesterdolmetschen.webp 1024w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/fluesterdolmetschen-300x225.webp 300w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/fluesterdolmetschen-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e17fd5e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"e17fd5e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-956370f elementor-widget elementor-widget-text-editor\" data-id=\"956370f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die KERN Austria bietet Ihnen als Full-Service-Dienstleister mit \u00fcber 50-j\u00e4hriger Erfahrung in der fremdsprachlichen Kommunikation und \u00fcber 50 Standorten weltweit professionelle Unterst\u00fctzung im Bereich der technischen Kommunikation sowie bei Ihren \u00dcbersetzungsprojekten. Gerne stellen wir Ihnen ebenfalls hochqualifizierte DolmetscherInnen f\u00fcr Ihre internationalen Konferenzen, Messeauftritte, Pressekonferenzen oder Gerichtsverhandlungen zur Seite.<\/p>\n<p>Bei kurz- sowie langfristigen Projekten stehen Ihnen unsere technischen RedakteurInnen, \u00dcbersetzerInnen und DolmetscherInnen gerne zur Verf\u00fcgung. Unser Team ber\u00e4t Sie umfassend und ermittelt gemeinsam mit Ihnen, wer Sie optimal bei Ihrem Vorhaben bzw. Projekt unterst\u00fctzen kann. Sie profitieren dabei von einer qualifizierten Beratung und bewahren gleichzeitig die volle Flexibilit\u00e4t beim Einsatz Ihres Spezialisten. Auf Wunsch k\u00f6nnen unsere ExpertInnen auch direkt vor Ort in Ihrem Unternehmen eingesetzt werden.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c6257e9 e-flex e-con-boxed e-con e-parent\" data-id=\"c6257e9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-fc0d16c e-con-full e-flex e-con e-child\" data-id=\"fc0d16c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-7a12588 e-con-full e-flex e-con e-child\" data-id=\"7a12588\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-be031a7 elementor-widget elementor-widget-heading\" data-id=\"be031a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Sie ben\u00f6tigen eine Arbeitnehmer\u00fcberlassung?<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8e9bcc9 elementor-widget elementor-widget-text-editor\" data-id=\"8e9bcc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir stellen Ihnen gerne einen professionellen Mitarbeitenden f\u00fcr Ihr Projekt zur Seite. Senden Sie uns Ihre Anfrage oder buchen Sie einen Online-Termin.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-55beaec elementor-align-center nounderline elementor-widget elementor-widget-button\" data-id=\"55beaec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#contact\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-arrow-right\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M190.5 66.9l22.2-22.2c9.4-9.4 24.6-9.4 33.9 0L441 239c9.4 9.4 9.4 24.6 0 33.9L246.6 467.3c-9.4 9.4-24.6 9.4-33.9 0l-22.2-22.2c-9.5-9.5-9.3-25 .4-34.3L311.4 296H24c-13.3 0-24-10.7-24-24v-32c0-13.3 10.7-24 24-24h287.4L190.9 101.2c-9.8-9.3-10-24.8-.4-34.3z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Jetzt Kontakt aufnehmen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3d91943 e-flex e-con-boxed e-con e-parent\" data-id=\"3d91943\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-540b883 e-con-full e-flex e-con e-child\" data-id=\"540b883\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-02dcb0d e-con-full e-flex e-con e-child\" data-id=\"02dcb0d\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5a3e321 elementor-widget elementor-widget-heading\" data-id=\"5a3e321\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ihre Vorteile im \u00dcberblick<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f0617b5 elementor-widget elementor-widget-text-editor\" data-id=\"f0617b5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die ExpertInnen von KERN Austria verf\u00fcgen \u00fcber das notwendige fachspezifische Know-how. Zus\u00e4tzlich bieten wir Ihnen ein breites Spektrum an Branchen, das unsere RedakteurInnen, \u00dcbersetzerInnen und DolmetscherInnen abdecken. Aufgrund ihrer Expertise und langj\u00e4hrigen Erfahrung f\u00e4llt eine Einarbeitungszeit weg \u2013 somit k\u00f6nnen Sie schnell vom Einsatz ihres Spezialisten profitieren und Ihr Projekt effizient ausf\u00fchren und planen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6dc1d18 e-con-full e-flex e-con e-child\" data-id=\"6dc1d18\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3e39c34 e-con-full e-flex e-con e-child\" data-id=\"3e39c34\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-caf8273 hyphen elementor-widget-mobile__width-inherit elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"caf8273\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Verantwortung:<\/strong> Als Arbeitgeber haben wir Verantwortung f\u00fcr unsere LeiharbeitnehmerInnen. Arbeitssicherheit und gesetzliches Handeln in jeder Hinsicht und jederzeit sind daher die Eckpfeiler unserer Arbeit.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>Branchen\u00fcbergreifende Erfahrung:<\/strong> Wir kennen die vielf\u00e4ltigen Herausforderungen der unterschiedlichsten Branchen bis ins Detail.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Transparente Kosten<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Fachspezifisches Know-how<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">Stetige Fort- und Weiterbildung unserer technischen RedakteurInnen, \u00dcbersetzerInnen und DolmetscherInnen<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-check\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M173.898 439.404l-166.4-166.4c-9.997-9.997-9.997-26.206 0-36.204l36.203-36.204c9.997-9.998 26.207-9.998 36.204 0L192 312.69 432.095 72.596c9.997-9.997 26.207-9.997 36.204 0l36.203 36.204c9.997 9.997 9.997 26.206 0 36.204l-294.4 294.401c-9.998 9.997-26.207 9.997-36.204-.001z\"><\/path><\/svg>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\"><strong>SpezialistInnen vor Ort:<\/strong> Einsatz von RedakteurInnen, \u00dcbersetzerInnen und DolmetscherInnen direkt in Ihrem Unternehmen bzw. bei Ihrer Veranstaltung.<\/span>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-3b00efb e-flex e-con-boxed e-con e-parent\" data-id=\"3b00efb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-389c23e e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"389c23e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInLeft&quot;}\">\n\t\t<div class=\"elementor-element elementor-element-643754c e-con-full e-flex e-con e-child\" data-id=\"643754c\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a45231f elementor-widget elementor-widget-heading\" data-id=\"a45231f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Partnerschaft mit IZS<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0cacfb9 elementor-widget elementor-widget-text-editor\" data-id=\"0cacfb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wir sind uns der Verantwortung gegen\u00fcber unseren LeiharbeitnehmerInnen bewusst. Durch die Partnerschaft mit IZS \u2013 dem Institut f\u00fcr Zahlungssicherheit \u2013 bieten wir v\u00f6llige Transparenz \u00fcber detaillierte Risikoinformationen und einen Nachweis \u00fcber unsere Zuverl\u00e4ssigkeit. Hier finden Sie weitere Informationen: <a href=\"http:\/\/www.izs.de\/kern-ag\" target=\"_blank\" rel=\"noopener\">www.izs.de\/kern-ag<\/a><\/p>\n<p>Gemeinsam arbeiten wir am Erfolg Ihrer Projekte \u2013 und das bei v\u00f6lliger Kostentransparenz!<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-cf4b70b e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"cf4b70b\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeInRight&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4d0a852 elementor-widget elementor-widget-image\" data-id=\"4d0a852\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/zeitarbeit.webp\" class=\"attachment-full size-full wp-image-11092\" alt=\"\" srcset=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/zeitarbeit.webp 1024w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/zeitarbeit-300x225.webp 300w, https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/zeitarbeit-768x576.webp 768w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-86e3141 e-flex e-con-boxed e-con e-parent\" data-id=\"86e3141\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-659d1f9 e-con-full e-flex e-con e-child\" data-id=\"659d1f9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-3df0bfb e-con-full e-flex e-con e-child\" data-id=\"3df0bfb\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;gradient&quot;}\">\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-50394f1 elementor-widget elementor-widget-heading\" data-id=\"50394f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">FAQ zur Arbeitnehmer\u00fcberlassung<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ee2f9e4 elementor-widget elementor-widget-heading\" data-id=\"ee2f9e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">H\u00e4ufige Fragen und Antworten<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-073537f elementor-widget elementor-widget-text-editor\" data-id=\"073537f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Die wichtigsten Fragen zur Arbeitnehmer\u00fcberlassung finden Sie hier in K\u00fcrze beantwortet.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-2ca4a32 e-flex e-con-boxed e-con e-parent\" data-id=\"2ca4a32\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e216fb9 elementor-widget elementor-widget-n-accordion\" data-id=\"e216fb9\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2370\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2370\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Was bedeutet Arbeitnehmer\u00fcberlassung bei KERN? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2370\" class=\"elementor-element elementor-element-f0c5ed7 e-con-full e-flex e-con e-child\" data-id=\"f0c5ed7\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5afc88a elementor-widget elementor-widget-text-editor\" data-id=\"5afc88a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Bei der Arbeitnehmer\u00fcberlassung stellt KERN Austria Ihnen qualifizierte Fachkr\u00e4fte \u2014 z.\u202fB. \u00dcbersetzerInnen, DolmetscherInnen oder technische RedakteurInnen \u2014 zeitweise oder projektbezogen \u2014 zur Verf\u00fcgung.\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2371\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2371\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Wann lohnt sich eine Arbeitnehmer\u00fcberlassung mit KERN? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2371\" class=\"elementor-element elementor-element-78f971d e-con-full e-flex e-con e-child\" data-id=\"78f971d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c41dac9 elementor-widget elementor-widget-text-editor\" data-id=\"c41dac9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Wenn Sie Auftragsspitzen abfangen m\u00fcssen, kurzfristig Kapazit\u00e4tsengp\u00e4sse haben oder f\u00fcr ein bestimmtes Projekt flexibel Fachkr\u00e4fte ben\u00f6tigen, bietet die Arbeitnehmer\u00fcberlassung schnelle, professionelle Unterst\u00fctzung ohne langfristige Bindung.\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2372\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2372\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Welche Fachkr\u00e4fte stellt KERN Austria zur Verf\u00fcgung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2372\" class=\"elementor-element elementor-element-f685eb4 e-con-full e-flex e-con e-child\" data-id=\"f685eb4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bdac48d elementor-widget elementor-widget-text-editor\" data-id=\"bdac48d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>KERN stellt erfahrene \u00dcbersetzerInnen, DolmetscherInnen und technische RedakteurInnen bereit \u2014 je nach Bedarf und Projekttyp, auch f\u00fcr langfristige Projekte.<\/p>\n<p>\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2373\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2373\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Sind die eingesetzten Fachkr\u00e4fte sofort einsatzf\u00e4hig? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2373\" class=\"elementor-element elementor-element-cc90a3e e-con-full e-flex e-con e-child\" data-id=\"cc90a3e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-96a3c0b elementor-widget elementor-widget-text-editor\" data-id=\"96a3c0b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ja \u2014 dank ihrer Erfahrung und Branchenkenntnis der SpezialistInnen von KERN entfallen lange Einarbeitungszeiten &#8211; Sie profitieren sofort von deren Fachwissen.<\/p>\n<p>\u00a0<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2374\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"5\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2374\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Kann die Fachkraft direkt bei uns vor Ort arbeiten? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2374\" class=\"elementor-element elementor-element-aa0afdb e-con-full e-flex e-con e-child\" data-id=\"aa0afdb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5295946 elementor-widget elementor-widget-text-editor\" data-id=\"5295946\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Ja \u2014 auf Wunsch k\u00f6nnen die SpezialistInnen auch direkt in Ihrem Unternehmen eingesetzt werden, um nahtlos in Ihre Prozesse integriert zu arbeiten.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2375\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"6\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2375\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> F\u00fcr welche Arten von Projekten eignet sich Arbeitnehmer\u00fcberlassung? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2375\" class=\"elementor-element elementor-element-6ab8233 e-con-full e-flex e-con e-child\" data-id=\"6ab8233\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5857dd7 elementor-widget elementor-widget-text-editor\" data-id=\"5857dd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Besonders geeignet ist sie bei kurzfristigen \u00dcbersetzungs\u2011 oder Dolmetschauftr\u00e4gen, w\u00e4hrend Messe\u2011 oder Konferenzzeiten, bei technischen Dokumentationsprojekten oder wenn personelle Kapazit\u00e4ten im Unternehmen tempor\u00e4r begrenzt sind.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2376\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"7\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2376\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><h3 class=\"e-n-accordion-item-title-text\"> Was sind die Vorteile gegen\u00fcber der Beauftragung eines klassischen \u00dcbersetzungsauftrags? <\/h3><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-up\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M240.971 130.524l194.343 194.343c9.373 9.373 9.373 24.569 0 33.941l-22.667 22.667c-9.357 9.357-24.522 9.375-33.901.04L224 227.495 69.255 381.516c-9.379 9.335-24.544 9.317-33.901-.04l-22.667-22.667c-9.373-9.373-9.373-24.569 0-33.941L207.03 130.525c9.372-9.373 24.568-9.373 33.941-.001z\"><\/path><\/svg><\/span>\n\t\t\t<span class='e-closed'><svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-chevron-down\" viewBox=\"0 0 448 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M207.029 381.476L12.686 187.132c-9.373-9.373-9.373-24.569 0-33.941l22.667-22.667c9.357-9.357 24.522-9.375 33.901-.04L224 284.505l154.745-154.021c9.379-9.335 24.544-9.317 33.901.04l22.667 22.667c9.373 9.373 9.373 24.569 0 33.941L240.971 381.476c-9.373 9.372-24.569 9.372-33.942 0z\"><\/path><\/svg><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2376\" class=\"elementor-element elementor-element-8a074b2 e-con-full e-flex e-con e-child\" data-id=\"8a074b2\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1d8503c elementor-widget elementor-widget-text-editor\" data-id=\"1d8503c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Arbeitnehmer\u00fcberlassung bietet maximale Flexibilit\u00e4t, direkte Integration der Fachperson in Ihr Team und h\u00e4ufig schnellere Reaktionszeiten \u2014 ideal, wenn Sie Kontrolle \u00fcber Prozesse, Umgang und Qualit\u00e4t w\u00fcnschen und Kapazit\u00e4ten flexibel steuern wollen.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<script type=\"application\/ld+json\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@type\":\"FAQPage\",\"mainEntity\":[{\"@type\":\"Question\",\"name\":\"Was bedeutet Arbeitnehmer\\u00fcberlassung bei KERN?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Bei der Arbeitnehmer\\u00fcberlassung stellt KERN Austria Ihnen qualifizierte Fachkr\\u00e4fte \\u2014 z.\\u202fB. \\u00dcbersetzerInnen, DolmetscherInnen oder technische RedakteurInnen \\u2014 zeitweise oder projektbezogen \\u2014 zur Verf\\u00fcgung.\\u00a0\"}},{\"@type\":\"Question\",\"name\":\"Wann lohnt sich eine Arbeitnehmer\\u00fcberlassung mit KERN?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Wenn Sie Auftragsspitzen abfangen m\\u00fcssen, kurzfristig Kapazit\\u00e4tsengp\\u00e4sse haben oder f\\u00fcr ein bestimmtes Projekt flexibel Fachkr\\u00e4fte ben\\u00f6tigen, bietet die Arbeitnehmer\\u00fcberlassung schnelle, professionelle Unterst\\u00fctzung ohne langfristige Bindung.\\u00a0\"}},{\"@type\":\"Question\",\"name\":\"Welche Fachkr\\u00e4fte stellt KERN Austria zur Verf\\u00fcgung?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"KERN stellt erfahrene \\u00dcbersetzerInnen, DolmetscherInnen und technische RedakteurInnen bereit \\u2014 je nach Bedarf und Projekttyp, auch f\\u00fcr langfristige Projekte.\\n\\u00a0\"}},{\"@type\":\"Question\",\"name\":\"Sind die eingesetzten Fachkr\\u00e4fte sofort einsatzf\\u00e4hig?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Ja \\u2014 dank ihrer Erfahrung und Branchenkenntnis der SpezialistInnen von KERN entfallen lange Einarbeitungszeiten &#8211; Sie profitieren sofort von deren Fachwissen.\\n\\u00a0\"}},{\"@type\":\"Question\",\"name\":\"Kann die Fachkraft direkt bei uns vor Ort arbeiten?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Ja \\u2014 auf Wunsch k\\u00f6nnen die SpezialistInnen auch direkt in Ihrem Unternehmen eingesetzt werden, um nahtlos in Ihre Prozesse integriert zu arbeiten.\"}},{\"@type\":\"Question\",\"name\":\"F\\u00fcr welche Arten von Projekten eignet sich Arbeitnehmer\\u00fcberlassung?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Besonders geeignet ist sie bei kurzfristigen \\u00dcbersetzungs\\u2011 oder Dolmetschauftr\\u00e4gen, w\\u00e4hrend Messe\\u2011 oder Konferenzzeiten, bei technischen Dokumentationsprojekten oder wenn personelle Kapazit\\u00e4ten im Unternehmen tempor\\u00e4r begrenzt sind.\"}},{\"@type\":\"Question\",\"name\":\"Was sind die Vorteile gegen\\u00fcber der Beauftragung eines klassischen \\u00dcbersetzungsauftrags?\",\"acceptedAnswer\":{\"@type\":\"Answer\",\"text\":\"Arbeitnehmer\\u00fcberlassung bietet maximale Flexibilit\\u00e4t, direkte Integration der Fachperson in Ihr Team und h\\u00e4ufig schnellere Reaktionszeiten \\u2014 ideal, wenn Sie Kontrolle \\u00fcber Prozesse, Umgang und Qualit\\u00e4t w\\u00fcnschen und Kapazit\\u00e4ten flexibel steuern wollen.\"}}]}<\/script>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen.<\/p>\n","protected":false},"author":11,"featured_media":8519,"parent":11047,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_relevanssi_hide_post":"","_relevanssi_hide_content":"","_relevanssi_pin_for_all":"","_relevanssi_pin_keywords":"","_relevanssi_unpin_keywords":"","_relevanssi_related_keywords":"","_relevanssi_related_include_ids":"","_relevanssi_related_exclude_ids":"","_relevanssi_related_no_append":"","_relevanssi_related_not_related":"","_relevanssi_related_posts":"","_relevanssi_noindex_reason":"","footnotes":""},"folder":[236],"class_list":["post-8518","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Arbeitnehmer\u00fcberlassung | MitarbeiterInnen f\u00fcr \u00dcbersetzungen<\/title>\n<meta name=\"description\" content=\"Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen. Hier anfragen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arbeitnehmer\u00fcberlassung | MitarbeiterInnen f\u00fcr \u00dcbersetzungen\" \/>\n<meta property=\"og:description\" content=\"Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen. Hier anfragen!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KernAG\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-20T13:19:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/\",\"name\":\"Arbeitnehmer\u00fcberlassung | MitarbeiterInnen f\u00fcr \u00dcbersetzungen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp\",\"datePublished\":\"2025-12-02T15:22:29+00:00\",\"dateModified\":\"2026-05-20T13:19:50+00:00\",\"description\":\"Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen. Hier anfragen!\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/#breadcrumb\"},\"inLanguage\":\"AT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/12\\\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp\",\"width\":1920,\"height\":1080,\"caption\":\"Gesch\u00e4ftstreffen im B\u00fcro mit Handschlag, symbolisiert Arbeitnehmer\u00fcberlassung von \u00dcbersetzern und Dolmetschern\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/arbeitnehmerueberlassung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Services\",\"item\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/services\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Arbeitnehmer\u00fcberlassung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#website\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"name\":\"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"AT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#organization\",\"name\":\"Kern AG\",\"alternateName\":\"Kern Global Language Services\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"AT\",\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"contentUrl\":\"https:\\\/\\\/www.e-kern.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/kern-ag-logo.svg\",\"width\":668,\"height\":181,\"caption\":\"Kern AG\"},\"image\":{\"@id\":\"https:\\\/\\\/www.e-kern.com\\\/de-at\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KernAG\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/kern-global-language-services\\\/\",\"https:\\\/\\\/www.xing.com\\\/pages\\\/kernagsprachendienste\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/KernLanguageServices\",\"https:\\\/\\\/www.instagram.com\\\/kern_ag\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Arbeitnehmer\u00fcberlassung | MitarbeiterInnen f\u00fcr \u00dcbersetzungen","description":"Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen. Hier anfragen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/","og_locale":"en_US","og_type":"article","og_title":"Arbeitnehmer\u00fcberlassung | MitarbeiterInnen f\u00fcr \u00dcbersetzungen","og_description":"Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen. Hier anfragen!","og_url":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/","og_site_name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","article_publisher":"https:\/\/www.facebook.com\/KernAG\/","article_modified_time":"2026-05-20T13:19:50+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/","url":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/","name":"Arbeitnehmer\u00fcberlassung | MitarbeiterInnen f\u00fcr \u00dcbersetzungen","isPartOf":{"@id":"https:\/\/www.e-kern.com\/de-at\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/#primaryimage"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/#primaryimage"},"thumbnailUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp","datePublished":"2025-12-02T15:22:29+00:00","dateModified":"2026-05-20T13:19:50+00:00","description":"Auf der Suche nach MitarbeiterInnen f\u00fcr \u00dcbersetzungen? Wir bieten ma\u00dfgeschneiderte Unterst\u00fctzung in sprachlichen Belangen. Hier anfragen!","breadcrumb":{"@id":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/#breadcrumb"},"inLanguage":"AT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/"]}]},{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/#primaryimage","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/12\/arbeitnehmerueberlassung-uebersetzer-dolmetscher.webp","width":1920,"height":1080,"caption":"Gesch\u00e4ftstreffen im B\u00fcro mit Handschlag, symbolisiert Arbeitnehmer\u00fcberlassung von \u00dcbersetzern und Dolmetschern"},{"@type":"BreadcrumbList","@id":"https:\/\/www.e-kern.com\/de-at\/services\/arbeitnehmerueberlassung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.e-kern.com\/de-at\/"},{"@type":"ListItem","position":2,"name":"Services","item":"https:\/\/www.e-kern.com\/de-at\/services\/"},{"@type":"ListItem","position":3,"name":"Arbeitnehmer\u00fcberlassung"}]},{"@type":"WebSite","@id":"https:\/\/www.e-kern.com\/de-at\/#website","url":"https:\/\/www.e-kern.com\/de-at\/","name":"\u00dcbersetzen und Dolmetschen in allen Weltsprachen | KERN AG","description":"","publisher":{"@id":"https:\/\/www.e-kern.com\/de-at\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.e-kern.com\/de-at\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"AT"},{"@type":"Organization","@id":"https:\/\/www.e-kern.com\/de-at\/#organization","name":"Kern AG","alternateName":"Kern Global Language Services","url":"https:\/\/www.e-kern.com\/de-at\/","logo":{"@type":"ImageObject","inLanguage":"AT","@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/","url":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","contentUrl":"https:\/\/www.e-kern.com\/wp-content\/uploads\/2025\/10\/kern-ag-logo.svg","width":668,"height":181,"caption":"Kern AG"},"image":{"@id":"https:\/\/www.e-kern.com\/de-at\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KernAG\/","https:\/\/www.linkedin.com\/company\/kern-global-language-services\/","https:\/\/www.xing.com\/pages\/kernagsprachendienste","https:\/\/www.youtube.com\/user\/KernLanguageServices","https:\/\/www.instagram.com\/kern_ag\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/pages\/8518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/comments?post=8518"}],"version-history":[{"count":10,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/pages\/8518\/revisions"}],"predecessor-version":[{"id":39309,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/pages\/8518\/revisions\/39309"}],"up":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/pages\/11047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media\/8519"}],"wp:attachment":[{"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/media?parent=8518"}],"wp:term":[{"taxonomy":"folder","embeddable":true,"href":"https:\/\/www.e-kern.com\/de-at\/wp-json\/wp\/v2\/folder?post=8518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}